{"id":183,"count":6,"description":"","link":"https:\/\/divingseasons.com\/es\/destinos-es\/maldives-es\/","name":"Maldives","slug":"maldives-es","taxonomy":"destination","parent":0,"meta":[],"acf":[],"thumbnail":{"width":1293,"height":1545,"file":"2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727.jpg","filesize":308150,"sizes":{"woocommerce_thumbnail":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-300x300.jpg","width":300,"height":300,"filesize":20104,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-100x100.jpg","width":100,"height":100,"filesize":5983,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-100x100.jpg"},"woocommerce_single":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-600x717.jpg","width":600,"height":717,"filesize":68281,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-600x717.jpg"},"medium":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-251x300.jpg","width":251,"height":300,"filesize":16340,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-251x300.jpg"},"large":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-857x1024.jpg","width":857,"height":1024,"filesize":131534,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-857x1024.jpg"},"thumbnail":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-150x150.jpg","width":150,"height":150,"filesize":8338,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-150x150.jpg"},"medium_large":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-768x918.jpg","width":768,"height":918,"filesize":107057,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-768x918.jpg"},"trip-thumb-size":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-374x226.jpg","width":374,"height":226,"filesize":21093,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-374x226.jpg"},"destination-thumb-size":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-600x810.jpg","width":600,"height":810,"filesize":76555,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-600x810.jpg"},"destination-thumb-trip-size":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-410x250.jpg","width":410,"height":250,"filesize":24399,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-410x250.jpg"},"activities-thumb-size":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-600x810.jpg","width":600,"height":810,"filesize":76555,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-600x810.jpg"},"trip-single-size":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-990x490.jpg","width":990,"height":490,"filesize":96055,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-990x490.jpg"},"tourm_85X85":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-85x85.jpg","width":85,"height":85,"filesize":5386,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-85x85.jpg"},"tourm_424X498":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-424x498.jpg","width":424,"height":498,"filesize":36764,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-424x498.jpg"},"tourm_420X347":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-420x347.jpg","width":420,"height":347,"filesize":30642,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-420x347.jpg"},"tourm_248X220":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-248x220.jpg","width":248,"height":220,"filesize":14333,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-248x220.jpg"},"1536x1536":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-1285x1536.jpg","width":1285,"height":1536,"filesize":273585,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-1285x1536.jpg"},"2048x2048":{"file":"pexels-asadphoto-1483053-2048x1237.jpg","width":2048,"height":1237,"filesize":318069,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-2048x1237.jpg"},"tourm-shop-single":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-580x580.jpg","width":580,"height":580,"filesize":60253,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-580x580.jpg"},"tourm-shop-thumb":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-100x106.jpg","width":100,"height":106,"filesize":6080,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-100x106.jpg"},"tourm-shop-small-image":{"file":"pexels-asadphoto-1483053-scaled-e1739789524727-294x312.jpg","width":294,"height":312,"filesize":19775,"mime_type":"image\/jpeg","source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1739789524727-294x312.jpg"},"full":{"file":"pexels-asadphoto-1483053-scaled-e1744790344410.jpg","width":1293,"height":1545,"source_url":"https:\/\/divingseasons.com\/wp-content\/uploads\/2025\/02\/pexels-asadphoto-1483053-scaled-e1744790344410.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"_links":{"self":[{"href":"https:\/\/divingseasons.com\/es\/wp-json\/wp\/v2\/destination\/183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divingseasons.com\/es\/wp-json\/wp\/v2\/destination"}],"about":[{"href":"https:\/\/divingseasons.com\/es\/wp-json\/wp\/v2\/taxonomies\/destination"}],"wp:post_type":[{"href":"https:\/\/divingseasons.com\/es\/wp-json\/wp\/v2\/trip?destination=183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}